{"id":389847,"date":"2026-06-14T14:34:22","date_gmt":"2026-06-14T18:34:22","guid":{"rendered":"https:\/\/www.rael.org\/la-mision-mas-sencilla-sonreir-y-cambiar-el-mundo\/"},"modified":"2026-06-26T20:29:08","modified_gmt":"2026-06-27T00:29:08","slug":"la-mision-mas-sencilla-sonreir-y-cambiar-el-mundo","status":"publish","type":"post","link":"https:\/\/www.rael.org\/es\/la-mision-mas-sencilla-sonreir-y-cambiar-el-mundo\/","title":{"rendered":"La misi\u00f3n m\u00e1s sencilla: sonre\u00edr y cambiar el mundo"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" lazyload=\"lazyload\" class=\"aligncenter wp-image-389586 size-large\" src=\"https:\/\/images.weserv.nl\/?url=www.rael.org\/wp-content\/uploads\/2026\/06\/June-14-Weekly-address-80ah-1024x576.jpg\" alt=\"\" width=\"800\" height=\"450\"><\/p>\n<p>Hoy tengo una peque\u00f1a sorpresa para ti. Hemos encontrado un <a href=\"https:\/\/www.youtube.com\/watch?v=Rt3pCrPsNWo\" target=\"_blank\" rel=\"noopener\">v\u00eddeo creado por IA<\/a> que refleja exactamente lo que somos. \u00bfQu\u00e9 somos? Mensajeros de los Elohim, s\u00ed. Pero, sobre todo, estamos creando una humanidad feliz. Nuestra misi\u00f3n es hacer que toda la humanidad sea pac\u00edfica, amorosa y feliz. Y este peque\u00f1o v\u00eddeo, hecho por alguien que ni siquiera es Raeliano, me hace muy feliz porque refleja qui\u00e9nes somos.      <\/p>\n<p>Los seres humanos somos tan est\u00fapidos. Todo est\u00e1 aqu\u00ed. La felicidad est\u00e1 aqu\u00ed, dentro de ti. Pero tienes que verla para encontrarla. Y la gente va corriendo de un lado a otro en una especie de carrera sin fin. &#8220;\u00bfD\u00f3nde est\u00e1 la felicidad? \u00bfD\u00f3nde est\u00e1 la felicidad?&#8221; Dentro de ti. Pero miran hacia fuera y la buscan. Toda la humanidad, millones de personas\u2026 Est\u00e1 justo ah\u00ed, pero la buscan fuera. &#8220;\u00bfQu\u00e9 puede hacerme feliz? \u00bfM\u00e1s dinero? \u00bfM\u00e1s poder? \u00bfUn coche nuevo? \u00bfUn trabajo nuevo? \u00bfUna pareja nueva?&#8221;         <\/p>\n<p>Nada.<\/p>\n<p>Porque la felicidad no est\u00e1 ah\u00ed fuera, como ya sabes. Siempre miras hacia fuera. Mira dentro de ti. Es muy, muy sencillo. Y la mejor forma de expresar tu felicidad es sonre\u00edr. Muy, muy dif\u00edcil, \u00bfeh? No hace falta ir a las mejores universidades. Solo tienes que sonre\u00edr. S\u00e9 tan feliz que tu felicidad se vuelva contagiosa. Cuanto m\u00e1s feliz est\u00e9s, m\u00e1s feliz har\u00e1s a la gente que te rodea. Muy dif\u00edcil. Solo una sonrisa.           <\/p>\n<p>Es muy dif\u00edcil. Solo con esa cara ya&#8230; <\/p>\n<p>La gente camina por la calle, deprimida. &#8220;\u00bfD\u00f3nde est\u00e1 la felicidad? \u00bfD\u00f3nde est\u00e1 la felicidad?&#8221;. Miles de suicidios cada d\u00eda. \u00bfPor qu\u00e9? Porque no son felices. Oh, tienen coches, pisos, novios, novias. Lo tienen todo. Pero no son felices. Y caminan por la calle como zombis, como fantasmas, como son\u00e1mbulos. Y de repente te ven. No te ven a ti. Ven tu sonrisa.           <\/p>\n<p>\u00bfEh? \u00bfEh? \u00bfEh? [como se dice en japon\u00e9s]   <\/p>\n<p>&#8220;\u00bfPor qu\u00e9 est\u00e1 sonriendo? Todo el mundo est\u00e1 triste. Seguro que \u00e9l tambi\u00e9n est\u00e1 triste, como todos los dem\u00e1s&#8221;. \u00bfEh? <\/p>\n<p>Est\u00e1s aqu\u00ed para provocar esto [las risas], \u00bfeh? Solo con una sonrisa. <\/p>\n<p>Vas por la calle. \u00bfCu\u00e1ntas personas tendr\u00e1n la sonrisa de Haachan? Puedes contarlas, \u00bfeh? Nadie. Caminan como robots. Tienen caras casi sin vida. Y, de repente, ven a Haachan, sonriendo sin motivo alguno. Pero eso cambia la vida de la gente. Y esa es nuestra misi\u00f3n. Cambiar este planeta es muy f\u00e1cil.         <\/p>\n<p>Sonr\u00ede. \u00a1Sonr\u00ede! \u00a1Ta-da-dee-da-da-da, sonr\u00ede! Solo sonr\u00ede.   <\/p>\n<p>Y es muy, muy poderoso. Y antes de ver este v\u00eddeo, te voy a contar un dato que he descubierto esta ma\u00f1ana. Unos investigadores de alto nivel en ciencia cu\u00e1ntica han descubierto algo. Bueno, creen que lo han descubierto, porque lo que han encontrado es incre\u00edble.   <\/p>\n<p>Un f\u00edsico cu\u00e1ntico dijo: &#8220;Es muy raro. Cuanto m\u00e1s nos adentramos en el mundo infinitamente peque\u00f1o de la f\u00edsica cu\u00e1ntica, m\u00e1s parece que las part\u00edculas, esas part\u00edculas infinitamente peque\u00f1as, se comportan como si alguien las estuviera observando&#8221;. No somos nosotros. Dicen &#8220;algo&#8221;. No dicen &#8220;alguien&#8221; porque no quieren dar pie a la idea de dios.   <\/p>\n<p>Todas las part\u00edculas se mueven de una forma que parece como si algo nos estuviera observando. Puedes relacionar esto con lo que dije la semana pasada. Los fotones se comportan de forma diferente cuando alguien los est\u00e1 observando y cuando nadie los est\u00e1 observando. Ninguna ciencia puede explicarlo. Y este cient\u00edfico aplic\u00f3 este descubrimiento a todas las part\u00edculas y \u00e1tomos del universo y dijo: &#8220;Por c\u00f3mo se comportan, es como si algo nos estuviera observando&#8221;.    <\/p>\n<p>Sue\u00f1a con eso.<\/p>\n<p>Y ahora, veamos c\u00f3mo puedes cambiar este planeta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy tengo una peque\u00f1a sorpresa para ti. Hemos encontrado un v\u00eddeo creado por IA que refleja exactamente lo que somos. \u00bfQu\u00e9 somos? Mensajeros de los Elohim, s\u00ed. Pero, sobre todo, estamos creando una humanidad feliz. Nuestra misi\u00f3n es hacer que toda la humanidad sea pac\u00edfica, amorosa y feliz. Y este peque\u00f1o v\u00eddeo, hecho por alguien [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6109],"tags":[],"class_list":["post-389847","post","type-post","status-publish","format-standard","hentry","category-weekly-address"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.rael.org\/es\/wp-json\/wp\/v2\/posts\/389847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rael.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rael.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rael.org\/es\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rael.org\/es\/wp-json\/wp\/v2\/comments?post=389847"}],"version-history":[{"count":1,"href":"https:\/\/www.rael.org\/es\/wp-json\/wp\/v2\/posts\/389847\/revisions"}],"predecessor-version":[{"id":389907,"href":"https:\/\/www.rael.org\/es\/wp-json\/wp\/v2\/posts\/389847\/revisions\/389907"}],"wp:attachment":[{"href":"https:\/\/www.rael.org\/es\/wp-json\/wp\/v2\/media?parent=389847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rael.org\/es\/wp-json\/wp\/v2\/categories?post=389847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rael.org\/es\/wp-json\/wp\/v2\/tags?post=389847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}